{"id":6775,"date":"2023-12-27T10:19:44","date_gmt":"2023-12-27T10:19:44","guid":{"rendered":"https:\/\/sites.hslu.ch\/werkstatt\/?p=6775"},"modified":"2025-01-29T19:30:07","modified_gmt":"2025-01-29T19:30:07","slug":"arduino-kit-motor-extension","status":"publish","type":"post","link":"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/","title":{"rendered":"Arduino Kit Motor Extension"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#187;dkw-section-lead&#187;][vc_row][vc_column width=&#187;2\/3&#8243; offset=&#187;vc_col-sm-offset-2&#8243;][vc_column_text]<span data-contrast=\"auto\">Das Arduino Kit Motor Extension beinhaltet erg\u00e4nzende Komponenten zum <a href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-basic\/\">Arduino Kit Basic<\/a>. Mit den Komponenten im Motor Extension Kit lassen sich Projekte realisieren, die Motoren oder Servos mit mehr Kraft oder eine pr\u00e4ziesere Steuerung von Motoren ben\u00f6tigen. Mit dem Kit lassen sich beispielsweise Zeichenmaschinen oder andere Projekte mit Schrittmotoren realisieren. Wenn du noch nie mit einem Arduino oder anderen Mikrokontroller gearbeitet hast, empfehlen wir dir die Recipes Start mit dem Arduino und Einstiegsaufgaben mit dem Arduino. F\u00fcr den Einstieg ben\u00f6tigst du ein Arduino Kit Basic. An der HSLU kannst du dieses k\u00fcnftig im Mediadock ausleihen, falls du an der HSLU DFK studierst oder im direkt im Makerspace in Rotkreuz, sofern du an der HSLU I studierst. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span>[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#187;dkw-section-content&#187;][vc_row][vc_column width=&#187;1\/3&#8243; offset=&#187;vc_col-lg-3&#8243; el_class=&#187;dkw-col-toc&#187;][vc_column_text css=&#187;&#187;][\/vc_column_text][\/vc_column][vc_column width=&#187;2\/3&#8243; el_class=&#187;dkw-col-content&#187; offset=&#187;vc_col-lg-6&#8243;][vc_column_text css=&#187;&#187;]<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#Uebersicht_Komponenten\" >\u00dcbersicht Komponenten<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#1_Potentiometer_10k_linear\" >1. Potentiometer 10k linear\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#2_Mikroschalter\" >2. Mikroschalter\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#3_Lichtschranke\" >3. Lichtschranke<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#_4_Getriebemotor_DC_3-6_V\" >\u00a04. Getriebemotor DC 3-6 V\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#5_Motor_DC_15_%E2%80%93_6V\" >5. Motor DC 1,5 \u2013 6V\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#6_CNC_Shield\" >6. CNC Shield\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#_7_Treiber_A4988\" >\u00a07. Treiber A4988<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#8_DF_Robot_Motorshield_Quad\" >8. DF Robot Motorshield Quad\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#_9_Servo_klein_5V\" >\u00a09. Servo klein 5V\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-11\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#_10_NEMA_Schrittmotor_12V\" >\u00a010. NEMA Schrittmotor 12V\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-12\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#11_Stellringe_Achsenkopplung\" >11. Stellringe \/ Achsenkopplung\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-13\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#12_DC_Netzteil_12V_4A\" >12. DC Netzteil 12V 4A\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-14\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#13_DC_Netzteil_3_%E2%80%93_12V_600mA_72_W\" >13. DC Netzteil 3 \u2013 12V 600mA (7.2 W)\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-15\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#14_Knetmasse\" >14. Knetmasse\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-16\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#15_Widerstaende\" >15. Widerst\u00e4nde\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-17\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#16_LED_divers\" >16. LED divers\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-18\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#17_Schraubenzieher\" >17. Schraubenzieher\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-19\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#18_Powerbank\" >18. Powerbank\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-20\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#19_Kabel_USB_Micro\" >19. Kabel USB Micro\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-21\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#20_Anschlusskabel_4pin_Schrittmotor\" >20. Anschlusskabel 4pin Schrittmotor\u00a0<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-22\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/arduino-kit-motor-extension\/#22_Servo_gross_48_%E2%80%93_6V\" >22. Servo gross 4.8 &#8211; 6V\u00a0<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Uebersicht_Komponenten\"><\/span><span id=\"komponenten\"><strong>\u00dcbersicht Komponenten<\/strong> <\/span><span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>[\/vc_column_text][vc_single_image image=&#187;7535&#8243; img_size=&#187;full&#187; onclick=&#187;link_image&#187; css=&#187;&#187;][vc_column_text css=&#187;&#187;]<span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"1_Potentiometer_10k_linear\"><\/span><span data-contrast=\"auto\">1. Potentiometer 10k linear<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>&nbsp;<\/p>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7561 size-full\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Potentiometer-10k-e1712842037987.png\" alt=\"\" width=\"250\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Das Potentiometer kann an einen analogen Eingang bei einem Mikrokontroller angeh\u00e4ngt werden wie dem Arduino Uno. Dreht man das Potentiometer, ver\u00e4ndert sich der Widerstand und damit das Eingangssignal beim Arduino. Der ver\u00e4ndernde Wert kann nun verwendet werden um beispielsweise eine LED zu faden oder auch die Spannung eines Motors und damit seine Geschwindigkeit zu ver\u00e4ndern. Das Potentiometer kann auch als Teil eines Controllers eingesetzt werden. Achtung es gibt lineare und logarithmische Potentiometer. Um beispielsweise die Lautst\u00e4rke einer Audioausgabe zu ver\u00e4ndern wird \u00fcblicherweise es ein logarithmisches Potentiometer verwendet.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Anschl\u00fcsse \/ Pinbelegung<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">links &#8211;&gt; GND Pin Mikrokontroller<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">mitte &#8211;&gt; analoger Pin Mikrokontroller<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">rechts &#8211;&gt; 5V Pin Mikrokontroller<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/10k-ohm-linear-drehpotentiometer-0-5w?search=potentiometer%2010k%20ohm\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"2_Mikroschalter\"><\/span><span data-contrast=\"auto\">2. Mikroschalter<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7577 size-full\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Mikroschalter-e1712842885467.png\" alt=\"\" width=\"394\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Dieser KW1-103 Rollenhebel Micro Schalter eignet sich perfekt f\u00fcr einen Endanschlag oder auch f\u00fcr einen Kontaktschalter einer T\u00fcre oder Fenster. Du kannst den Schalter auch f\u00fcr andere Arduino Projekte als Input einsetzen z.B. als T\u00fcrkontakt einer Alarmanlage. Der Schalter kann auch unabh\u00e4ngig vom Arduino ben\u00fctzt werden, um einen Stromkreislauf bei der Bet\u00e4tigung des Schalters zu schliessen und damit beispielsweise einen Motor ein\/auszuschalten.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/kw1-103-7-micro-rollenschalter-endschalter?search=schalter\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"3_Lichtschranke\"><\/span><span data-contrast=\"auto\">3. Lichtschranke<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"><br \/>\n<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7547 size-full\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Lichtschranke-e1712842674687.png\" alt=\"\" width=\"184\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Die schwarze Lichtschranke kann als Input an den Arduino angeschlossen werden. Damit l\u00e4sst sich beispielsweise eine interaktive Spendenkasse bauen, die auf das Einwerfen von M\u00fcnzen reagiert, indem beispielweise LEDs ihre Farbe \u00e4ndern oder ein Sound \u00fcber ein Piezolautsprecher abgespielt wird. Sobald sich etwas in der Mitte der Gabel befindet, ver\u00e4ndert sich das Signal am Arduino Pin. Diese Ver\u00e4nderung kann im Arduinoprogramm ausgelesen und im Code verwendet werden.\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/optischer-endschalter-lichtschranke-mit-kabel?search=lichtschran\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"><br \/>\n<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"_4_Getriebemotor_DC_3-6_V\"><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a04. <\/span><span data-contrast=\"auto\">Getriebemotor DC 3-6 V<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7542 size-full\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Getriebemotor-e1712841962370.png\" alt=\"\" width=\"250\" height=\"163\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Der Getriebemotor kann auch unabh\u00e4ngig vom Arduino verwendet werden, in diesem Fall muss er aber mit einer Batterie, Akku oder Netzteil betrieben werden. Die Spannung kann von 3 \u2013 6 V varieren. Mit der Ver\u00e4nderung der Spannung ver\u00e4ndert sich auch die Geschwindigkeit und die Kraft des Getriebemotors. Der Getriebemotor ist \u00fcber ein Getriebe (im blauen Geh\u00e4use) \u00fcbersetzt, was den Motor langsamer und st\u00e4rker macht also ohne Getriebe. Das Innengewinde in der Achse des Motors l\u00e4sst es zu, dass sich einfach Teile wie beispielsweise Zahnr\u00e4der an der Achse befestigen lassen. Die Spannung kann von 3 \u2013 6 V varieren.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Angeschlossen an den Arduino dient der Getriebemotor als Output und man kann damit beispielsweise einen simplen Roboter bauen. Mit einem Motortreiber oder Motorshield l\u00e4sst sich auch die Richtung des Motors und dessen Geschwindigkeit ansteuern.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/dc-3v-6v-1-90-vollmetall-getriebemotor?search=getriebemotor\"><span data-contrast=\"none\">Bestellink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"5_Motor_DC_15_%E2%80%93_6V\"><\/span><span data-contrast=\"auto\">5. Motor DC 1,5 \u2013 6V<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-6637 alignnone\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2022\/08\/Motor_DC_a-e1719841717298.png\" alt=\"\" width=\"148\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Der DC-Motor ist sehr schnell und er wird am besten f\u00fcr Projekte eingesetzt, die nicht viel Kraft ben\u00f6tigen. Um etwas an der Achse des Motors zu befestigen, k\u00f6nnen L\u00fcsterklemmen verwendet werden. Da der Motor bereits mit sehr wenig Strom l\u00e4uft, kann der Motor auch mit einer kleinen Solarzelle betrieben werden. Der Motor kann beispielsweise als Schlaginstrument verwendet werden, so verwendet beispielsweise <\/span><a href=\"https:\/\/zimoun.net\/\"><span data-contrast=\"none\">Zimoun<\/span><\/a><span data-contrast=\"auto\"> die Motoren in vielen seiner Installationen. Der Motor kann unabh\u00e4ngig oder in Kombination mit dem Arduino verwendet werden.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Angeschlossen an den Arduino dient der DC-Motor als Output. Mit einem Motortreiber oder Motorshield l\u00e4sst sich auch die Richtung des Motors und dessen Geschwindigkeit ansteuern.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/dc-motor-1-6v-130-size?search=motor\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"6_CNC_Shield\"><\/span><span data-contrast=\"auto\">6. CNC Shield<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7538 size-full\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-CNC-Shield-e1724948646124.png\" alt=\"\" width=\"346\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Das CNC Shield erm\u00f6glicht es Schrittmotoren anzusteuern. Diese Motoren funktionieren anders als der Getriebe und der simple DC-Motor und sind nicht unabh\u00e4ngig von einer Steuerung verwendbar.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">In der Kombination von Arduino, Schrittmotoren und dem CNC-Shield lassen sich beispielsweise Zeichenmaschinen bauen oder andere Projekte die mehr Kraft ben\u00f6tigen oder eine pr\u00e4zise Steuerung der Motoren. Damit werden Achsensteuerungen m\u00f6glich beispielsweise f\u00fcr einen 3D Drucker, eine CNC-Maschine oder einen Schneidplotter.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/cnc-shield-a4988-arduino-fur-3d-drucker-und-frasmaschinen-grbl?search=cnc%20shield\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"_7_Treiber_A4988\"><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a07. <\/span>Treiber A4988<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7567 size-full\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Treiber-CNC-Shield-e1724948751273.png\" alt=\"\" width=\"205\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Die Treiber werden f\u00fcr das CNC-Shield ben\u00f6tigt. Wenn sie bei falscher Anwendung \u00fcberhitzen oder aus anderen Gr\u00fcnden besch\u00e4digt werden, k\u00f6nnen sie ersetzt werden, ohne dass das gesamte Shield entsorgt werden muss.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/a4988-schrittmotor-treiber-stepper-driver-modul\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<h4><span class=\"ez-toc-section\" id=\"8_DF_Robot_Motorshield_Quad\"><\/span><span data-contrast=\"auto\">8. DF Robot Motorshield Quad<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7560\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Motorshield-e1724948834370.png\" alt=\"\" width=\"247\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Das Quad-Motor-Treiber-Shield f\u00fcr Arduino ist f\u00fcr die Verwendung mit 5V und 3,3V Controllern konzipiert. Es kann gleichzeitig bis zu vier DC-Motoren mit 8 Pins steuern.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/quad-dc-motor-driver-shield-fur-arduino?search=motor%20shield\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"_9_Servo_klein_5V\"><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a09. <\/span><span data-contrast=\"auto\">Servo klein 5V<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6581\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2022\/08\/Servo_Mini_-e1719841658785.png\" alt=\"\" width=\"257\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Dieser kleine Servo l\u00e4uft mit 5V Spannung und kann \u00fcber einen Mikrokontroller wie das Arduino Uno als Output angesteuert werden. Mit der Arduino Servo Library kann der Servo die Achse an genaue Positionen von 0 &#8211; 180\u00b0 drehen. Damit k\u00f6nnen kleine genaue Bewegungen ausgef\u00fchrt werden. Der Servo wird beispielsweise f\u00fcr Anzeigen (beispielsweise eine Wetteranzeige) verwendet oder bei einem kleinen Roboter, um die Richtung zu steuern indem die R\u00e4der auf eine bestimmte Seite gedreht werden.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Der Servo wird wie folgt an einen Mikrokontroller angeschlossen: Kabel Servo orange (digitaler Pin (PWM), braun (GND Pin), rot (5V Pin)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Verwandte Kits und Komponenten<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Im Motorkit findest du auch noch ein gr\u00f6sseres Servo mit mehr Leistung.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559737&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/tower-pro-micro-servo-9g-sg90?search=servo%205v\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"_10_NEMA_Schrittmotor_12V\"><\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a010. <\/span><span data-contrast=\"auto\">NEMA Schrittmotor 12V<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7563\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Schrittmotor-e1724948908303.png\" alt=\"\" width=\"246\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Diese NEMA Schrittmotoren sind sehr leise und k\u00f6nnen gr\u00f6ssere Lasten bewegen bei richtiger \u00dcbersetzung. Im Gegensatz zu den DC-Motoren ist eine Verwendung ohne Treiber nicht m\u00f6glich und die Programmierung ist etwas komplizierter. Mit dem CNC-Shield f\u00fcr den Arduino Mikrokontroller k\u00f6nnen gleichzeitig sogar mehrere Schrittmotoren angesteuert werden. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Die Schrittmotoren werden in den meisten 3D Druckern und CNC Maschinen verwendet. Mit den Schrittmotoren lassen sich pr\u00e4zise Bewegungen und Geschwindigkeiten umsetzen, was es beispielsweise erlaubt, eine Zeichenmaschine zu bauen. Um die Position des Schrittmotors zu kalibrieren wird h\u00e4ufig ein Mikroschalter verwendet, der beispielsweise das Ende einer Achse oder den Start einer Bewegung an den Mikrokontroller signalisieren kann. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/creality-42-40-stepper-motor-nema-17-schrittmotor?search=nema%20schritt\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"11_Stellringe_Achsenkopplung\"><\/span><span data-contrast=\"auto\">11. Stellringe \/ Achsenkopplung<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7544\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Kopplung-Achse-Schrittmotor-e1724948942689.png\" alt=\"\" width=\"296\" height=\"250\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7566\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Stellring-e1724948977935.png\" alt=\"\" width=\"249\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Die Stellringe und Achsenkopplungen erm\u00f6glichen es, dass auf einfache Weise Material wie Holz- oder Metallst\u00e4be als Achsenverl\u00e4ngerungen an den Schrittmotoren befestigt werden k\u00f6nnen. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/o5x8mm-bohranschlag\"><span data-contrast=\"none\">Bestelllink Bastelgarage Stellring<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/5mm-5mm-flexible-aluminium-kupplung-mit-stiftschrauben?search=kupplung\"><span data-contrast=\"none\">Bestelllink Bastelgarage Achsenkopplung<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"12_DC_Netzteil_12V_4A\"><\/span><span data-contrast=\"auto\">12. DC Netzteil 12V 4A<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7540\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-DC-Netzteil-2A-e1724949028820.png\" alt=\"\" width=\"219\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Das Netzteil liefert Strom mit Spannung 12V und gr\u00f6sserer Leistung. Dadurch lassen sich beispielsweise mehrere Schrittmotoren \u00fcber das CNC-Shield mit gen\u00fcgend Spannung und Leistung versorgen. Sind Komponenten an einem Netzteil angeh\u00e4ngt, die eigentlich mehr Leistung ben\u00f6tigen w\u00fcrde, kann das Netzteil heiss werden und es kann zu Unstimmigkeiten in der Funktion f\u00fchren, da nicht alle Teile mit der optimalen St\u00e4rke an Strom versorgt werden k\u00f6nnen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/12v-dc-4000ma-netzteil-ac-dc-adapter-5-5mm-2-1mm-stecker?search=netzteil\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"13_DC_Netzteil_3_%E2%80%93_12V_600mA_72_W\"><\/span><span data-contrast=\"auto\">13. DC Netzteil 3 \u2013 12V 600mA (7.2 W)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7539\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-DC-Netzteil-0.6A-e1724949100444.png\" alt=\"\" width=\"210\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Das Netzteil liefert Strom mit Spannung zwischen 3V \u2013 12V und eine Stromst\u00e4rke von 600mA. Das Netzeil ist also nicht auf grosse Lasten (beispielsweise f\u00fcr das Betreiben von Schrittmotoren) ausgelegt. Die ben\u00f6tigte Voltzahl l\u00e4sst sich am Netzteil einstellen. (siehe Anzeige auf dem Netzteil). Dabei ist es wichtig zu wissen, wie viel Spannung eine Komponente ben\u00f6tigt und wieviel Spannung die Komponente maximal vertr\u00e4gt. Stellt man die Spannung zu hoch ein f\u00fcr die Komponente, kann diese zerst\u00f6rt werden. Bei Komponenten, wie dem DC-Motor, der mit einer Spannung von 3 \u20136 V betrieben werden kann, kann man durch die Ver\u00e4nderung der Spannung auch die Geschwindigkeit des Motors minimal einstellen. Allerdings kann es sein, dass bei niederer Spannung auch die Kraft des Motors nachl\u00e4sst. Sind Komponenten an einem Netzteil angeh\u00e4ngt, die eigentlich mehr Leistung ben\u00f6tigen w\u00fcrde, kann das Netzteil heiss werden und es kann zu Unstimmigkeiten in der Funktion f\u00fchren, da nicht alle Teile mit der optimalen St\u00e4rke an Strom versorgt werden k\u00f6nnen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/12v-dc-4000ma-netzteil-ac-dc-adapter-5-5mm-2-1mm-stecker?search=netzteil\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\"><br \/>\n<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"14_Knetmasse\"><\/span><span data-contrast=\"auto\">14. Knetmasse<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7543\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Knetmasse-e1724949130419.png\" alt=\"\" width=\"239\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Die Knetmasse dient zum schnellen Verbinden verschiedener Komponenten und erm\u00f6glicht damit schnelle Tests f\u00fcr Prototypen ohne die Teile bereits langfristig miteinander zu verbinden.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.jumbo.ch\/de\/bastelshop\/giessen-modellieren\/knetbeton-beton-paste\/staedtler-noris-club-plastilin-knete\/p\/6955348\"><span data-contrast=\"none\">Bestelllink Jumbo<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"15_Widerstaende\"><\/span><span data-contrast=\"auto\">15. Widerst\u00e4nde<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6623\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2022\/08\/Widerstand_1kOhm_b-e1719843404665.png\" alt=\"\" width=\"30\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Widerst\u00e4nde werden dort ben\u00f6tigt, wo Bauteile im Einsatz sind, die nur wenig Spannung ben\u00f6tigen und bei zu hoher Spannung zerst\u00f6rt w\u00fcrden. Ein klassisches Beispiel daf\u00fcr sind LEDs. Sie ertragen oft nur wenig Spannung und somit braucht man h\u00e4ufig Widerst\u00e4nde um die Ausgangsspannung zu reduzieren. Der Widerstand sollte exakt oder h\u00f6her gew\u00e4hlt werden als ben\u00f6tigt. Bei einem zu hohen Widerstand schwindet zwar vielleicht die Leistung, (bei einer LED beispielsweise die Helligkeit) aber daf\u00fcr ist die Komponente sicher vor einer zu hohen Spannung gesch\u00fctzt. Widerst\u00e4nde k\u00f6nnen in Serie geschalten werden, womit sich der Wert der Widerst\u00e4nde addiert. Die Widerst\u00e4nde sind jedoch nur f\u00fcr die Reduktion von kleinen Spannungsmengen konzipiert. Wenn man gr\u00f6ssere Spannungsunterschiede hat, sollte man die Schaltung anders aufbauen, ein anderes Netzteil verwenden oder ein Spannungswandlermodul verwenden.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Die meisten Widerst\u00e4nde haben optisch 4 bis 6 farbige Ringe. Anhand der Ringe l\u00e4sst sich der Wert des Widerstands ablesen. Die Widerst\u00e4nde k\u00f6nnen jedoch auch \u00fcber ein Multimeter gemessen werden. Widerstandsrechner gibt es viele Online. Hier ein Beispiel f\u00fcr einen <\/span><a href=\"https:\/\/www.digikey.de\/de\/resources\/conversion-calculators\/conversion-calculator-resistor-color-code\"><span data-contrast=\"none\">Rechner von digikey<\/span><\/a><span data-contrast=\"auto\">.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/widerstand-set-300-stk-220-1k-1mohm-1-4w-1-genauigkeit?search=widerstand\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"16_LED_divers\"><\/span><span data-contrast=\"auto\">16. LED divers<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6605\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2022\/08\/LED_b-e1719843074963.png\" alt=\"\" width=\"250\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">LEDs (lichtemittierende Diode) sind kleine Leuchtkomponenten und es gibt sie in verschiedensten Farben und Gr\u00f6ssen. Die LEDs im Arduino Basic Kit sind 5mm gross. Wenn sie mit 5V betrieben werden sollen, beispielsweise durch den 5V Ausgang des Arduinos ist ein 220 Ohm Vorwiderstand Standard. F\u00fcr die maximal zul\u00e4ssige Stromaufnahme rechnet man bei den Standard 5mm LEDs mit 30mA. LEDs k\u00f6nnen parallel oder auch seriell geschaltet werden. Dabei sollte man aber beachten, dass die unterschiedlichen Farben minime Unterschiede in der Spannung aufweisen und somit bei verschiedenen Farben in einer parallelen Schaltung der Strom nur durch die Farbe mit der geringsten Spannung und somit dem geringsten Widerstand fliesst. So passiert es oft, dass dann eine Farbe sehr hell leuchtet und die anderen fast gar nicht. Es gibt auch LEDs mit mehr Leistung, also heller leuchten, so beispielsweise LEDs die mit 12 V Spannung laufen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">TIPP: Beim 13. digitalen Pin vom Arduino Uno ist bereits ein Vorwiderstand eingebaut und somit kannst du die LED hier direkt mit dem langen Bein (+) beim Pin13 einstecken und das kurze Bein (-) beim benachbarten GND &#8211; Ground Pin. Damit musst du das Programm nat\u00fcrlich auch das Programm so anpassen das der Pin13 angesteuert wird.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Ansch\u00fcsse \/ Pinbelegungen<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">kurzes Bein LED &#8211;&gt; GND Pin des Mikrokontrollers<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">langes Bein LED &#8211;&gt; via Widerstand oder falls PIN 13 direkt an den digitalen Pin eines Miktrokontrollers<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Eine LED kann in den meisten F\u00e4llen auch mit einer 3V Batterie betrieben werden. Die Batterie ist in dem Falle jedoch nur Stromversorgung und es kann nichts aktiv gesteuert werden.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/led-grun-5mm?search=led%20gr%C3%BCn\"><span data-contrast=\"none\">Bestelllink Bastelgarage gr\u00fcne LEDs<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/led-rot-5mm\"><span data-contrast=\"none\">Bestelllink Bastelgarage rote LEDs<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/led-gelb-5mm?search=led%20gelb\"><span data-contrast=\"none\">Bestelllink Bastelgarage gelbe LEDs<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/led-weiss-5mm?search=led%20weiss\"><span data-contrast=\"none\">Bestelllink Bastelgarage weisse LEDs<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"17_Schraubenzieher\"><\/span><span data-contrast=\"auto\">17. Schraubenzieher<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6614\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2022\/08\/Schraubenzieher_mini_b-e1719843445702.png\" alt=\"\" width=\"80\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Den kleinen Schraubenzieher braucht es beispielsweise f\u00fcr die Ben\u00fctzung des Screwshields und auch andere Komponenten ben\u00f6tigen den Schraubenzieher um die Schraubverbindungen anzuziehen und zu l\u00f6sen.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/mini-schraubenzieher-schlitz-2-0mm?search=schraubenzie\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"18_Powerbank\"><\/span><span data-contrast=\"auto\">18. Powerbank<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7536\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Akku-e1724949311117.png\" alt=\"\" width=\"257\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Dieses 1&#215;18650 Batterie Shield eignet sich perfekt um deinen Mikrokontroller mit Strom zu versorgen. Der Lithium Akku l\u00e4sst sich direkt \u00fcber den Micro-USB Anschluss nachladen. Damit bist du in der Anwendung mobil und nicht auf ein Netzteil angewiesen.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:0,&quot;335559739&quot;:240,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Achtung: <\/span><\/b><span data-contrast=\"auto\">Beim Einsetzen der 18650 Lithium Batterien die Polarit\u00e4t + und \u2013 beachten, ansonsten wird der Ladechip zerst\u00f6rt!<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Anwendung:<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Nachdem die 18650 Zellen eingesetzt wurden, muss das Shield Kurzzeitig \u00fcber den Micro USB oder USB Typ-C mit Strom versorgt werden (erst dann schaltet es sich ein). Durch kurzzeitiges dr\u00fccken auf die Seitliche Taste (K1) kann der Ladezustand gepr\u00fcft werden. Zum Ausschalten der 5V und 3V Ausg\u00e4nge muss die Seitliche Taste (K1) mehr als 3 Sekunden gedr\u00fcckt werden. Zum Einschalten einfach die Seitliche Taste (K1) kurzzeitig dr\u00fccken.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/1x18650-lithium-batterie-shield-5v-3a-3v-1a\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;134233117&quot;:false,&quot;134233118&quot;:false,&quot;201341983&quot;:0,&quot;335551550&quot;:0,&quot;335551620&quot;:0,&quot;335559738&quot;:240,&quot;335559739&quot;:240,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"19_Kabel_USB_Micro\"><\/span><span data-contrast=\"auto\">19. Kabel USB Micro<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-6620\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2022\/08\/USB_Kabel_Micro_b-e1719843638413.png\" alt=\"\" width=\"250\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Das Micro USB Kabel kann sowohl zum programmieren vom Arduino Micro Mikrokontroller und vom Wemos D1 mini Mikrokontroller verwendet werden. Dabei kann \u00fcber das Kabel ein Programm auf die Kontroller geladen werden und gleichzeitig werden sie mit Strom versorgt. Sobald das Programm auf den Kontroller geladen ist, kann das Kabel auf verwendet werden um den Kontroller extern mit Strom zu versorgen beispielsweise \u00fcber einen USB-Stecker oder eine Powerbank.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/0-3m-micro-usb-2-0-kabel-blau?search=Micro%20USB\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"20_Anschlusskabel_4pin_Schrittmotor\"><\/span><span data-contrast=\"auto\">20. Anschlusskabel 4pin Schrittmotor<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7537\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Anschlusskabel-Schrittmotoren-e1724949369659.png\" alt=\"\" width=\"388\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Die Anschlusskabel sind dazu da, die Schrittmotoren mit dem CNC-Shield zu verbinden.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/6p-ph2-0-auf-4p-xh2-54-schrittmotor-kabel-1m-nema17?search=schrittmotor%20kabel\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a021. <\/span><span data-contrast=\"auto\">Krokoklemmenkabel<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Mit den Krokolemmenkabeln kann man gut Strom leitende Materialien verbinden. So kann beispiel Alufolie mit einem Jumperwire verbunden werden, das dann \u00fcber ein Breadboard weiter als Teil einer Schaltung gebraucht werden kann. Auch Komponenten die keinen geeigneten Anschluss f\u00fcr das Breadboard haben, dienen die Krokoklemmenkabel als \u00dcberbr\u00fcckungsm\u00f6glichkeit zum Schaltkreislauf auf dem Breadboard.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/10-stuck-messleitungen-mit-krokodilklemmen-in-verschiedenen-farben?search=krok\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a><\/p>\n<p><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<h4><span class=\"ez-toc-section\" id=\"22_Servo_gross_48_%E2%80%93_6V\"><\/span><span data-contrast=\"auto\">22. Servo gross 4.8 &#8211; 6V<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p><span data-contrast=\"auto\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-7564\" src=\"https:\/\/sites.hslu.ch\/werkstatt\/wp-content\/uploads\/sites\/13\/2023\/12\/Arduino-MK-Servo-gross-4.8-6V-e1724949402312.png\" alt=\"\" width=\"334\" height=\"250\" \/><\/span><\/p>\n<p><span data-contrast=\"auto\">Dieser\u00a0Servo l\u00e4uft mit 4.8 &#8211; 6V\u00a0Spannung und ist st\u00e4rker als der kleine Servo mit 5V. Der Servo kann \u00fcber einen Mikrokontroller wie das Arduino Uno angesteuert werden. Damit der Servo gen\u00fcgend Spannung und Stromst\u00e4rke bekommt muss der Servo \u00fcber ein separates Netzteil mit Strom versorgt werden, damit er funktioniert. <\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Der Servo wird wie folgt an einen Mikrokontroller angeschlossen:<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Kabel Servo orange &#8211;&gt; digitaler Pin Mikrokontroller(PWM \/ Output)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Kabel Servo braun &#8211;&gt; direkt an Minus des Netzteils<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Kabel Servo rot &#8211;&gt; direkt ans Plus des Netzteils<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><b><span data-contrast=\"auto\">Verwandte Kits und Komponenten<\/span><\/b><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Im Motorkit findest du auch noch ein gr\u00f6sseres Servo mit mehr Leistung.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"https:\/\/www.bastelgarage.ch\/tower-pro-micro-servo-9g-sg90?search=servo%205v\"><span data-contrast=\"none\">Bestelllink Bastelgarage<\/span><\/a><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559685&quot;:-20,&quot;335559737&quot;:-20,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><a href=\"#komponenten\">\u2191 ZUR\u00dcCK<\/a>[\/vc_column_text][\/vc_column][vc_column width=&#187;1\/3&#8243; el_class=&#187;dkw-col-micro&#187; offset=&#187;vc_col-lg-3&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#187;dkw-dontprint&#187;][vc_row disable_element=&#187;yes&#187;][vc_column][vc_column_text]<span style=\"color: red\">\u2014 \u2014 \u2014 INFO: In beiden nachfolgenden Post Grids die passenden Recipies und die passenden Talks\u00a0 ausw\u00e4hlen \u2014 \u2014 \u2014<br \/>\n<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<\/p>\n<h2>Passende Recipies<\/h2>\n<p>[\/vc_column_text][vc_basic_grid post_type=&#187;ids&#187; element_width=&#187;2&#8243; gap=&#187;10&#8243; item=&#187;517&#8243; css=&#187;&#187; grid_id=&#187;vc_gid:1738178987070-67d9618b-9ab2-8&#8243; include=&#187;6784, 6780, 7684, 7680&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#187;dkw-dontprint&#187;][vc_row][vc_column][vc_column_text css=&#187;&#187;]<\/p>\n<h2>Passende Tools<\/h2>\n<p>[\/vc_column_text][vc_basic_grid post_type=&#187;ids&#187; element_width=&#187;2&#8243; gap=&#187;10&#8243; item=&#187;517&#8243; grid_id=&#187;vc_gid:1738178987070-961b37bf-dd7e-0&#8243; include=&#187;4098&#8243;][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section el_class=&#187;dkw-section-lead&#187;][vc_row][vc_column width=&#187;2\/3&#8243; offset=&#187;vc_col-sm-offset-2&#8243;][vc_column_text]Das Arduino Kit Motor Extension beinhaltet erg\u00e4nzende Komponenten zum Arduino Kit Basic. Mit den Komponenten im Motor Extension Kit lassen sich [&hellip;]<\/p>\n","protected":false},"author":102,"featured_media":7535,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[15,13],"tags":[],"class_list":["post-6775","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mediadock","category-tools"],"acf":[],"_links":{"self":[{"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/posts\/6775","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/users\/102"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/comments?post=6775"}],"version-history":[{"count":33,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/posts\/6775\/revisions"}],"predecessor-version":[{"id":8832,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/posts\/6775\/revisions\/8832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/media\/7535"}],"wp:attachment":[{"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/media?parent=6775"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/categories?post=6775"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/tags?post=6775"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}