{"id":4451,"date":"2023-01-30T13:33:53","date_gmt":"2023-01-30T13:33:53","guid":{"rendered":"https:\/\/sites.hslu.ch\/werkstatt\/?p=4451"},"modified":"2024-02-12T14:28:41","modified_gmt":"2024-02-12T14:28:41","slug":"stribig","status":"publish","type":"post","link":"https:\/\/sites.hslu.ch\/werkstatt\/stribig\/","title":{"rendered":"Striebig"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_section el_class=&#187;dkw-section-lead&#187;][vc_row][vc_column width=&#187;2\/3&#8243; offset=&#187;vc_col-sm-offset-2&#8243;][vc_column_text]Vertikale Wandplattenfr\u00e4se[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#187;dkw-section-content&#187;][vc_row][vc_column width=&#187;1\/3&#8243; el_class=&#187;dkw-col-toc&#187; offset=&#187;vc_col-lg-3&#8243;][\/vc_column][vc_column width=&#187;2\/3&#8243; el_class=&#187;dkw-col-content&#187; offset=&#187;vc_col-lg-6&#8243;][vc_column_text]<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<span class=\"ez-toc-title-toggle\"><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/stribig\/#Saegen\" >S\u00e4gen<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/stribig\/#Erklaerung\" >Erkl\u00e4rung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/stribig\/#Verwendung\" >Verwendung<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/sites.hslu.ch\/werkstatt\/stribig\/#Was_ist_moeglich\" >Was ist m\u00f6glich?<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h3><span class=\"ez-toc-section\" id=\"Saegen\"><\/span>S\u00e4gen<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<h4><span class=\"ez-toc-section\" id=\"Erklaerung\"><\/span>Erkl\u00e4rung<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Die Plattens\u00e4ge, wie sie eigentlich heisst, dient dazu, grosse Platten auf Format zu schneiden. Dabei kann sich das Fr\u00e4sen-Aggregat waagrecht oder senkrecht ausrichten und in beide Richtungen schneiden. Die Maschine ist f\u00fcr grosse Platten konzipiert und eignet sich deshalb nicht gut f\u00fcr Teile unter 30cm. Die Maschine arbeitet halb automatisch. Dadurch ist es nie notwendig, dem Fr\u00e4seblatt nahe zu kommen. Um die Sicherheit zu gew\u00e4hrleisten, h\u00e4lt man bei dieser Maschine die H\u00e4nde ebenfalls nie n\u00e4her als 15cm zum Fr\u00e4seblatt oder zur Schutzhaube. Obwohl die Maschine f\u00fcr Platten gemacht ist. Kann man mit ihr auch Massivholz schneiden. Die Stribig darf nur mit Absprache mit der Werkstattbetreuung selbst\u00e4ndig genutzt werden.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Verwendung\"><\/span>Verwendung<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>F\u00fcr den Formatschnitt von grossen Platten.<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Was_ist_moeglich\"><\/span>Was ist m\u00f6glich?<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li>Gerade Schnitte, paralell zu einer Kannte.<\/li>\n<li>Abgesetzte Schnitte.<\/li>\n<li>Genauer Zuschnitt von Platten<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][vc_column width=&#187;1\/3&#8243; el_class=&#187;dkw-col-micro&#187; offset=&#187;vc_col-lg-3&#8243;][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#187;dkw-section-content&#187;][vc_row][vc_column width=&#187;1\/3&#8243; el_class=&#187;dkw-col-toc&#187; offset=&#187;vc_col-lg-3&#8243;][vc_column_text][\/vc_column_text][\/vc_column][vc_column width=&#187;2\/3&#8243; el_class=&#187;dkw-col-content&#187; offset=&#187;vc_col-lg-6&#8243;][vc_video link=&#187;<a href=\"https:\/\/www.youtube.com\/watch?v=PaFYUtXzTok&#038;list=PL-hx5jmZwjraUBnGds3uoJpd6oXI6FcDG&#038;index=2&#038;#8243\" rel=\"nofollow\">https:\/\/www.youtube.com\/watch?v=PaFYUtXzTok&#038;list=PL-hx5jmZwjraUBnGds3uoJpd6oXI6FcDG&#038;index=2&#038;#8243<\/a>; title=&#187;Suva Sicherheitshinweise&#187;][\/vc_column][vc_column width=&#187;1\/3&#8243; el_class=&#187;dkw-col-micro&#187; offset=&#187;vc_col-lg-3&#8243;][\/vc_column][\/vc_row][\/vc_section]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_section el_class=&#187;dkw-section-lead&#187;][vc_row][vc_column width=&#187;2\/3&#8243; offset=&#187;vc_col-sm-offset-2&#8243;][vc_column_text]Vertikale Wandplattenfr\u00e4se[\/vc_column_text][\/vc_column][\/vc_row][\/vc_section][vc_section el_class=&#187;dkw-section-content&#187;][vc_row][vc_column width=&#187;1\/3&#8243; el_class=&#187;dkw-col-toc&#187; offset=&#187;vc_col-lg-3&#8243;][\/vc_column][vc_column width=&#187;2\/3&#8243; el_class=&#187;dkw-col-content&#187; offset=&#187;vc_col-lg-6&#8243;][vc_column_text] S\u00e4gen Erkl\u00e4rung Die Plattens\u00e4ge, wie sie eigentlich heisst, dient dazu, grosse Platten [&hellip;]<\/p>\n","protected":false},"author":53,"featured_media":4862,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[27,13],"tags":[],"class_list":["post-4451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-holz","category-tools"],"acf":[],"_links":{"self":[{"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/posts\/4451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/comments?post=4451"}],"version-history":[{"count":9,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/posts\/4451\/revisions"}],"predecessor-version":[{"id":6965,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/posts\/4451\/revisions\/6965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/media\/4862"}],"wp:attachment":[{"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/media?parent=4451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/categories?post=4451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.hslu.ch\/werkstatt\/wp-json\/wp\/v2\/tags?post=4451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}