{"id":9529,"date":"2022-05-09T13:20:00","date_gmt":"2022-05-09T11:20:00","guid":{"rendered":"https:\/\/sites.hslu.ch\/architektur\/?p=9529"},"modified":"2026-04-29T08:48:34","modified_gmt":"2026-04-29T06:48:34","slug":"kleinwohnformen","status":"publish","type":"post","link":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/","title":{"rendered":"Kleinwohnformen"},"content":{"rendered":"\n<h3 class=\"wp-block-heading\">Wohn- und Lebensraum mit Potenzial?<\/h3>\n\n\n\n<p class=\"is-style-lead-text\">Klimawandel, Bauland-Mangel und steigende Mieten \u2013 der Immobiliensektor steht vor grossen Herausforderungen. Ein interdisziplin\u00e4res Forschungsprojekt untersucht das Potenzial von Kleinwohnformen wie Tiny Houses, Micro-Apartments und Mobileheimen. Der Fokus liegt auf dem Spannungsfeld von Individualisierung und Verdichtung im Kontext der Nachhaltigkeit.<\/p>\n\n\n\n<p>Welches Potenzial haben Kleinwohnformen im Spannungsfeld zwischen Individualisierung und Verdichtung im Kontext der Nachhaltigkeit?<\/p>\n\n\n\n<p>Die von Innosuisse gef\u00f6rderte, interdisziplin\u00e4re Studie der Hochschule Luzern verdeutlicht, dass Kleinwohnformen (bis zu 30 Quadratmeter f\u00fcr eine Person und bis zu 15 Quadratmeter f\u00fcr jede weitere Person) verschiedene Potenziale f\u00fcr eine nachhaltige Entwicklung bieten k\u00f6nnen.<\/p>\n\n\n\n<p>Politische und baurechtliche Massnahmen sowie innovative Finanzierungsmodelle k\u00f6nnen \u2013 je nach Ausgestaltung \u2013&nbsp;Kleinwohnformen als nachhaltige und zukunftsf\u00e4hige Wohnl\u00f6sungen f\u00f6rdern, um ihre Rolle im Spannungsfeld zwischen Individualisierung und Verdichtung zu st\u00e4rken. Die vom Projektteam entwickelten Visionen f\u00fcr st\u00e4dtische und l\u00e4ndliche R\u00e4ume pr\u00e4sentieren m\u00f6gliche Modellprojekte, die auf den Forschungsergebnissen basieren.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Projektergebnisse<\/h3>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Deskriptiver-Ueberblick-Schweiz_1920px-1024x683.jpg\" alt=\"\" class=\"wp-image-39132 size-full\" srcset=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Deskriptiver-Ueberblick-Schweiz_1920px-1024x683.jpg 1024w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Deskriptiver-Ueberblick-Schweiz_1920px-300x200.jpg 300w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Deskriptiver-Ueberblick-Schweiz_1920px-768x512.jpg 768w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Deskriptiver-Ueberblick-Schweiz_1920px-1536x1025.jpg 1536w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Deskriptiver-Ueberblick-Schweiz_1920px-600x400.jpg 600w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Deskriptiver-Ueberblick-Schweiz_1920px.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Deskriptiver \u00dcberblick Schweiz<\/strong><br><\/p>\n\n\n\n<p>Die Auswertung der Umfrage zeigt, dass Kleinwohnformen in der Schweiz durchaus Potenzial haben. Rund die H\u00e4lfte der Befragten hat bereits Erfahrungen mit Kleinwohnformen oder kann sich vorstellen, in einer solchen zu leben. <br>Ebenso wird dabei deutlich, dass sich bisherige und zuk\u00fcnftige Bewohner:innen in ihren Antworten teilweise deutlich unterscheiden.<strong> <\/strong>Ein Grund daf\u00fcr d\u00fcrfte insbesondere sein, dass etwa erfahrene Personen die jeweilige Frage in Bezug auf ihre tats\u00e4chliche Wohnsituation beziehungsweise in Bezug auf ihre Erfahrungen mit Kleinwohnformen beantworten, w\u00e4hrend sich die Interessierten auf ein hypothetisches oder Wunsch-Szenario beziehen.&nbsp;<br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/01\/HSLU-Kleinwohnformen-Deskriptiver-berblick-Schweiz.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Schlussbericht \u00abDeskriptiver \u00dcberblick Schweiz\u00bb<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Inter-und-Transdisziplinaere-Ergebnisse_1920px-1024x683.jpg\" alt=\"\" class=\"wp-image-39118 size-full\" srcset=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Inter-und-Transdisziplinaere-Ergebnisse_1920px-1024x683.jpg 1024w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Inter-und-Transdisziplinaere-Ergebnisse_1920px-300x200.jpg 300w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Inter-und-Transdisziplinaere-Ergebnisse_1920px-768x512.jpg 768w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Inter-und-Transdisziplinaere-Ergebnisse_1920px-1536x1024.jpg 1536w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Inter-und-Transdisziplinaere-Ergebnisse_1920px-600x400.jpg 600w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Inter-und-Transdisziplinaere-Ergebnisse_1920px.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Inter- und transdisziplin\u00e4re Ergebnisse<\/strong><br>Ziel der vorliegenden Studie ist es, das Potenzial von Kleinwohnformen im Spannungsfeld von Individualisierung und Verdichtung im Kontext der Nachhaltigkeit inter- und transdisziplin\u00e4r zu betrachten. Der Schwerpunkt liegt auf der Analyse von Nachfrage- und Nutzer:innensegmenten von Kleinwohnformen, basierend auf soziodemografischen Daten.<br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/04\/HSLU-Kleinwohnformen-Inter-und-transdisziplinaere-Ergebnisse.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Schlussbericht \u00abInter- und transdisziplin\u00e4re Ergebnisse\u00bb<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Praxisbeispiele-und-typologische-Merkmale_Web_1920px-1024x682.jpg\" alt=\"\" class=\"wp-image-39122 size-full\" srcset=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Praxisbeispiele-und-typologische-Merkmale_Web_1920px-1024x682.jpg 1024w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Praxisbeispiele-und-typologische-Merkmale_Web_1920px-300x200.jpg 300w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Praxisbeispiele-und-typologische-Merkmale_Web_1920px-768x512.jpg 768w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Praxisbeispiele-und-typologische-Merkmale_Web_1920px-1536x1023.jpg 1536w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Praxisbeispiele-und-typologische-Merkmale_Web_1920px-600x400.jpg 600w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Praxisbeispiele-und-typologische-Merkmale_Web_1920px.jpg 1591w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Praxisbeispiele und typologische Merkmale<\/strong><br>Gem\u00e4ss Studie z\u00e4hlt eine Wohneinheit dann zu den Kleinwohnformen, wenn die Individualfl\u00e4che f\u00fcr eine Person maximal 30 m2 betr\u00e4gt bzw. f\u00fcr jede weitere Person zus\u00e4tzlich maximal 15 m2 dazu kommen.&nbsp;<br>Kleinwohnformen k\u00f6nnen als Einfamilienhaus oder als Mehrfamilienhaus genutzt werden. Je nachdem besteht das Geb\u00e4ude aus einer Wohneinheit oder mehreren Wohneinheiten, die miteinander kombiniert werden. Abh\u00e4ngig von unterschiedlichen baulich-r\u00e4umlichen Aspekten werden sechs architektonische Typologien von Kleinwohnformen festgelegt.<br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/04\/HSLU-Kleinwohnformen-Praxisbeispiele-und-typologische-Merkmale.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Schlussbericht \u00abPraxisbeispiele und typologische Merkmale\u00bb<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Rechtlicher-Rahmen-und-Prozess_Web_1920px-1024x683.jpg\" alt=\"\" class=\"wp-image-39124 size-full\" srcset=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Rechtlicher-Rahmen-und-Prozess_Web_1920px-1024x683.jpg 1024w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Rechtlicher-Rahmen-und-Prozess_Web_1920px-300x200.jpg 300w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Rechtlicher-Rahmen-und-Prozess_Web_1920px-768x512.jpg 768w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Rechtlicher-Rahmen-und-Prozess_Web_1920px-1536x1025.jpg 1536w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Rechtlicher-Rahmen-und-Prozess_Web_1920px-600x400.jpg 600w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Rechtlicher-Rahmen-und-Prozess_Web_1920px.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Rechtlicher Rahmen und Prozess<\/strong><br>Obgleich Kleinwohnformen im Hochbau zunehmend an Popularit\u00e4t gewinnen, stellen sie nach wie vor eine Randtypologie dar, sodass gegenw\u00e4rtig keine eigenst\u00e4ndige Gesetzgebung sowie angepasste Beurteilungsmodelle existieren.<br>Die vorliegende Studie hat zum Ziel, die baurechtlichen und raumplanungsrelevanten Grundlagen f\u00fcr Kleinwohnformen zu erfassen, das Verdichtungspotenzial f\u00fcr unterschiedliche Anwendungsf\u00e4lle aufzuzeigen sowie mit dem Wissen \u00fcber Erfordernisse und Hindernisse die Risiken in der Planung und Umsetzung von Kleinwohnformen zu reduzieren.<br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/01\/HSLU-Kleinwohnformen-Rechtlicher-Rahmen-und-Prozess.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download des Schlussberichts \u00abRechtlicher Rahmen und Prozess\u00bb<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Finanzierungsaspekte_1920px-1024x683.jpg\" alt=\"\" class=\"wp-image-39134 size-full\" srcset=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Finanzierungsaspekte_1920px-1024x683.jpg 1024w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Finanzierungsaspekte_1920px-300x200.jpg 300w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Finanzierungsaspekte_1920px-768x512.jpg 768w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Finanzierungsaspekte_1920px-1536x1024.jpg 1536w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Finanzierungsaspekte_1920px-600x400.jpg 600w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Finanzierungsaspekte_1920px.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Finanzierungsaspekte<\/strong><br>Kleinwohnformen k\u00f6nnen eine attraktive Wohnform f\u00fcr Personen mit kleinem Budget darstellen. Denn aufgrund ihrer kleinen Fl\u00e4che k\u00f6nnen Kleinwohnformen gegen\u00fcber traditionellen Wohnformen g\u00fcnstiger sein, sowohl zur Miete als auch zum Eigentum. Allerdings gibt es neben diesen und weiteren Chancen auch potenzielle Herausforderungen bez\u00fcglich der Finanzierung.<br>In der Studie werden diese Chancen und Herausforderungen dargestellt. Dabei werden zwei Sichtweisen beleuchtet. Zum einen die Sicht einer Bank, die die Vor- und Nachteile in Zusammenhang mit einer Hypothekarvergabe aufzeigt, zum anderen die Sicht verschiedener Expert:innen.<br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/01\/HSLU-Kleinwohnformen-Finanzierungsaspekte.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Schlussbericht \u00abFinanzierungsaspekte\u00bb<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Oekologische-Nachhaltigkeit_1920px-1024x683.jpg\" alt=\"\" class=\"wp-image-39120 size-full\" srcset=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Oekologische-Nachhaltigkeit_1920px-1024x683.jpg 1024w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Oekologische-Nachhaltigkeit_1920px-300x200.jpg 300w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Oekologische-Nachhaltigkeit_1920px-768x512.jpg 768w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Oekologische-Nachhaltigkeit_1920px-1536x1024.jpg 1536w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Oekologische-Nachhaltigkeit_1920px-600x400.jpg 600w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Oekologische-Nachhaltigkeit_1920px.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Nachhaltigkeit und \u00d6kobilanz<\/strong><br>Inwiefern Kleinwohnformen nachhaltiges Wohnen erm\u00f6glichen \u2013 wie vielfach versprochen \u2013 wurde in dieser Studie untersucht. Aus den Ergebnissen geht hervor, dass sich die Umweltwirkungen der Kleinwohnform-Typologien erheblich voneinander unterscheiden. So entstehen z. B. durch die Typologie \u00abVorgefertigtes Modul\u00bb 75 Prozent mehr Umweltbelastungspunkte als durch das \u00abFeste Haus\u00bb.<br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/04\/HSLU-Kleinwohnformen-oekologische-Nachhaltigkeit.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Schlussbericht \u00ab\u00d6kologische Nachhaltigkeit\u00bb<\/a><br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/04\/HSLU-Kleinwohnformen-oekologische-Nachhaltigkeit-Datengrundlage.xlsx\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Datengrundlage \u00f6kologische Nachhaltigkeit (Excel)<\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Soziodemografische-Profile_Standort_1920-1024x683.jpg\" alt=\"\" class=\"wp-image-39126 size-full\" srcset=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Soziodemografische-Profile_Standort_1920-1024x683.jpg 1024w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Soziodemografische-Profile_Standort_1920-300x200.jpg 300w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Soziodemografische-Profile_Standort_1920-768x512.jpg 768w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Soziodemografische-Profile_Standort_1920-1536x1025.jpg 1536w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Soziodemografische-Profile_Standort_1920-600x400.jpg 600w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Soziodemografische-Profile_Standort_1920.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Soziodemografische Profile der Nachfragesegmente<\/strong><br>Mittels einer breiten Datenerhebung bei insgesamt 1\u2018211 Personen und einer statistischen Auswertung werden unterschiedliche Modelle von soziodemografischen Profile der Nachfrage- und Nutzer:innensegmente gesch\u00e4tzt. Zum einen werden diese bez\u00fcglich unterschiedlicher Standorte wie Stadt\/urbane Gemeinden, Agglomerationsgemeinden im suburbanen Raum sowie l\u00e4ndliche Gemeinden nahe am Dorf-\/Gemeindezentrum\/Weiler beschrieben, zum anderen zeigen sie den Unterschied zwischen den unterschiedlichen Typologien Apartment, festes Haus, vorgefertigtes Modul, Fahrzeug und Anh\u00e4nger.<br>Die Zusammenstellungen machen pro Kategorie Aussagen zum Interessensgrad, zur Demografie, zur Nachfrage und zum Motiv sowie zu verschiedenen thematischen Schwerpunkten.<br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/01\/HSLU-Kleinwohnformen-Soziodemografische-Profile-Standorte.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Schlussbericht \u00abSoziodemografische Profile (Standorte)\u00bb<\/a><br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/01\/HSLU-Kleinwohnformen-Soziodemografische-Profile-Typologien.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Schlussbericht \u00abSoziodemografische Profile (Typologien)\u00bb <\/a><\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-media-text is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:32% auto\"><figure class=\"wp-block-media-text__media\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Vision-Buttisholz_1920px-1024x683.jpg\" alt=\"\" class=\"wp-image-39128 size-full\" srcset=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Vision-Buttisholz_1920px-1024x683.jpg 1024w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Vision-Buttisholz_1920px-300x200.jpg 300w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Vision-Buttisholz_1920px-768x512.jpg 768w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Vision-Buttisholz_1920px-1536x1024.jpg 1536w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Vision-Buttisholz_1920px-600x400.jpg 600w, https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Vision-Buttisholz_1920px.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p><strong>Visionen f\u00fcr eine urbane und rurale Umsetzung<\/strong><\/p>\n\n\n\n<p>Basierend auf den Projektergenissen wurden f\u00fcr die Gemeinde Buttisholz (LU) sowie f\u00fcr das Stadtquartier Z\u00fcrich-Affoltern Visionen erarbeitet.<br>Die Vision f\u00fcr die Gemeinde <strong>Buttisholz L\u00e4ngacher<\/strong> im Kanton Luzern fokussiert auf die Integration von Kleinwohnformen in das bestehende d\u00f6rfliche Netzwerk. Die Kleinwohnformen sollen zur Verdichtung beitragen und einen ressourcenschonenden Lebensstil erm\u00f6glichen. Zielgruppen sind \u00e4ltere Menschen nach der Familienphase, junge Erwachsene, die im Dorf bleiben m\u00f6chten, sowie Personen, die Wohnen und Landwirtschaft verbinden wollen.Die Vision f\u00fcr die neue Siedlung <strong>St\u00f6ckengasse<\/strong> in <strong>Z\u00fcrich-Affoltern<\/strong> zielt darauf ab,<strong> <\/strong>flexible und modulare Wohnl\u00f6sungen f\u00fcr unterschiedliche Lebensphasen und Familienstrukturen zu schaffen. Diese Wohnformen sollen insbesondere Familien mit Kindern, getrennt lebende Eltern und betreutes Wohnen f\u00fcr Kinder und Jugendliche unterst\u00fctzen.<br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/01\/HSLU-Kleinwohnformen-Vision-Lngacher-Buttisholz-2.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Vision Buttisholz<\/a><br><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/01\/HSLU-Kleinwohnformen-Vision-Stckengasse-Zrich-2.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">\u2013 Download Vision Z\u00fcrich-Affoltern<\/a><br><\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"Forschungsergebnisse-im-Dialog-mit-der-Praxis\">Forschungsergebnisse im Dialog mit der Praxis<\/h3>\n\n\n\n<p>Das Ziel der angewandten Forschung besteht darin, die in der Projektphase gewonnenen Erkenntnisse in die Praxis zur\u00fcckzuf\u00fchren und so einen konkreten Nutzen f\u00fcr Wirtschaft, Gesellschaft oder Institutionen zu schaffen. Ein zentraler Weg, um dieses Wissen zu transferieren, ist die Teilnahme an Konferenzen und Tagungen. Dort werden Forschungsergebnisse pr\u00e4sentiert, mit Experten diskutiert und in ein breiteres Netzwerk eingebracht. So gelangen neue Erkenntnisse schneller in praktische Anwendungen, der Austausch zwischen Forschung und Praxis wird gef\u00f6rdert und die Weiterentwicklung der jeweiligen Fachgebiete unterst\u00fctzt.<\/p>\n\n\n\n<p>Wir freuen uns besonders dar\u00fcber, dass wir zur Pr\u00e4sentation der Ergebnisse aus dem Innosuisse-Projekt an mehreren Fachveranstaltungen eingeladen wurden. Unter anderem durften wir unsere Arbeiten am Forum Raumwissenschaften 2025 sowie an der Tagung von EspaceSuisse Zentralschweiz einem breiten Fachpublikum vorstellen und diskutieren. Diese Einladungen zeigen nicht nur das Interesse an unseren Forschungsergebnissen, sondern bieten zugleich wertvolle Gelegenheiten, die gewonnenen Erkenntnisse direkt mit Praxisakteur:innen und Expert:innen zu teilen und weiterzuentwickeln.<\/p>\n\n\n\n<p>Die Teilnahme an den Veranstaltungen und der Austausch mit Fachpersonen haben uns gezeigt, wie stark das Potenzial kompakter Wohnl\u00f6sungen im Praxisfeld anklingt. In den Gespr\u00e4chen wurde sp\u00fcrbar, dass solche Ans\u00e4tze einen wertvollen Beitrag zur Bew\u00e4ltigung der Wohnraumknappheit leisten und bestehende Strategien sinnvoll erg\u00e4nzen k\u00f6nnen. F\u00fcr uns Forschende war dieser Dialog besonders bereichernd. Er hat uns motiviert, uns weiterhin mit dem Thema zu befassen und in Zukunft gemeinsam mit der Praxis an tragf\u00e4higen L\u00f6sungen zu arbeiten.<br><br><strong><a href=\"https:\/\/www.curem.uzh.ch\/de\/events\/fachveranstaltungen\/Raumwissenschaften-2025.html\" target=\"_blank\" rel=\"noreferrer noopener\">Forum Raumwissenschaften 2025: Mehr Wohnraum \u2013 weniger Bauen?<\/a><\/strong><\/p>\n\n\n\n<p>Das diesj\u00e4hrige <strong>Forum Raumwissenschaften<\/strong>, organisiert vom CUREM der Universit\u00e4t Z\u00fcrich, brachte rund 60 ausgew\u00e4hlte Fachpersonen aus Immobilienwirtschaft, Verwaltung, Wissenschaft und NGOs zusammen. Ziel des j\u00e4hrlich stattfindenden \u00abinvited-only\u00bb-Workshops ist es, den Austausch unter zentralen Akteur:innen der Raumentwicklung zu f\u00f6rdern und gemeinsam evidenzbasierte L\u00f6sungsans\u00e4tze f\u00fcr aktuelle Herausforderungen zu entwickeln. Im Fokus der Durchf\u00fchrung 2025 stand das Thema <strong>\u00abMehr Wohnraum \u2013 weniger Bauen?<\/strong>\u00bb und damit die Frage, wie zus\u00e4tzlicher Wohnraum geschaffen werden kann, ohne weiter ungebremst zu bauen. Im Zentrum standen Strategien des Weiterbauens, der intelligenten Fl\u00e4chennutzung sowie neue Wohnmodelle, die bestehende Strukturen besser nutzen.<\/p>\n\n\n\n<p>Unser <strong>Vortrag<\/strong> <strong>\u00abKleinwohnformen \u2013 Potenziale f\u00fcr Stadt und Land?\u00bb <\/strong>zeigte auf, wie kompakte Wohnl\u00f6sungen sowohl im urbanen Kontext als auch im l\u00e4ndlichen Raum neue M\u00f6glichkeiten er\u00f6ffnen. Anhand aktueller Beispiele und Erkenntnisse diskutierten wir, wie Kleinwohnformen zu einer ressourcenschonenden, sozial vielf\u00e4ltigen und r\u00e4umlich effizienten Siedlungsentwicklung beitragen k\u00f6nnen \u2013 und welche Rahmenbedingungen ihre Umsetzung erleichtern.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.espacesuisse.ch\/de\/veranstaltung\/tagung-wohnen-im-wandel-wege-aus-der-wohnungsknappheit\" target=\"_blank\" rel=\"noreferrer noopener\">Tagung \u00abWohnen im Wandel \u2013 Wege aus der Wohnungsknappheit\u00bb von EspaceSuisse Zentralschweiz<\/a><\/strong><\/p>\n\n\n\n<p>Die diesj\u00e4hrige Tagung <strong>\u00abWohnen im Wandel \u2013 Wege aus der Wohnungsknappheit\u00bb<\/strong> von EspaceSuisse Zentralschweiz widmete sich einer der dr\u00e4ngendsten Herausforderungen der Raumentwicklung: dem akuten Mangel an bezahlbarem und geeignetem Wohnraum. Vertreter:innen aus Raumplanung, Gemeinden, Kantonen, Immobilienwirtschaft und Forschung diskutierten gemeinsam, wie die Transformation des Wohnens gelingen kann \u2013 unter engen r\u00e4umlichen, \u00f6kologischen und sozialen Rahmenbedingungen.<br>Die Tagung beleuchtete zentrale Faktoren, die den Wohnungsmarkt heute pr\u00e4gen: steigende Nachfrage, beschr\u00e4nkte Baulandreserven, hohe Regulierungsdichte sowie ver\u00e4nderte Lebensstile und Haushaltsformen. Im Mittelpunkt standen praxisnahe L\u00f6sungswege, wie Gemeinden und Kantone neue Wohnraumangebote erm\u00f6glichen, bestehende Siedlungen weiterentwickeln und planerische Instrumente gezielt einsetzen k\u00f6nnen, um Wohnraum zu sichern und Wohnqualit\u00e4t zu erhalten.<br>Mit Fachinputs, Praxisbeispielen und themenspezifischen Workshops schaffte die Veranstaltung einen Raum f\u00fcr den Austausch zwischen Entscheidungstr\u00e4ger:innen und Expert:innen \u2013 und zeigte auf, wie kooperative Planung sowie ein gemeinsames Verst\u00e4ndnis der Herausforderungen zu wirksamen Handlungsm\u00f6glichkeiten f\u00fchren k\u00f6nnen.<\/p>\n\n\n\n<p>Im Rahmen der Tagung leiteten wir die<strong> Gruppendiskussion <\/strong>zum Thema <strong>\u00abDer Beitrag von Kleinwohnformen zur Innenentwicklung und zur m\u00f6glichen Entsch\u00e4rfung der Wohnungsknappheit\u00bb<\/strong>. Der Workshop setzte sich mit der Frage auseinander, inwiefern Wohnmodelle wie Clusterwohnungen, Microapartments oder Tiny Houses einen nachhaltigen Beitrag zur gesetzlichen Verdichtung und zur Bereitstellung von dringend ben\u00f6tigtem Wohnraum leisten k\u00f6nnen.<\/p>\n\n\n\n<p>Gemeinsam mit den Teilnehmenden diskutieren wir:<\/p>\n\n\n\n<ul class=\"wp-block-list is-style-list-dash\">\n<li>welche r\u00e4umlichen, sozialen und \u00f6kologischen Potenziale Kleinwohnformen bieten,<\/li>\n\n\n\n<li>wie Gemeinden geeignete Standorte identifizieren und Nachfrage einsch\u00e4tzen k\u00f6nnen,<\/li>\n\n\n\n<li>welche baurechtlichen Rahmenbedingungen entscheidend sind,<\/li>\n\n\n\n<li>und wie Kantone eine unterst\u00fctzende Rolle \u00fcbernehmen k\u00f6nnen \u2013 etwa durch Beratung, Regelwerksanpassungen oder kooperative Entwicklungsprozesse.<\/li>\n<\/ul>\n\n\n\n<p>Ziel der Gruppendiskussion war es, konkrete Schnittstellen zwischen Raumplanung, Gemeindepraxis und Wohnraumentwicklung sichtbar zu machen und herauszuarbeiten, wie Kleinwohnformen als Teil einer diversifizierten Wohnstrategie wirken k\u00f6nnen.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Weiterf\u00fchrende Links<\/h3>\n\n\n\n<p>\u2013 <a href=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/elisabeth-hat-kein-bett\/\" target=\"_blank\" rel=\"noreferrer noopener\">Neuer Beitrag auf dem HUB der HSLU Soziale Arbeit<\/a><br>\u2013&nbsp;<a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/forschung\/ausgewaehlte-projekte\/kleinwohnformen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Projekt auf der HSLU-Webseite<\/a><br>\u2013 <a href=\"https:\/\/sites.hslu.ch\/architektur\/rebuild-ukraine\/\" target=\"_blank\" rel=\"noreferrer noopener\">Workshop zu Kleinwohnformen im Rahmen des CAS \u00abRebuild Ukraine\u00bb<\/a><br>\u2013 <a href=\"https:\/\/hub.hslu.ch\/soziale-arbeit\/elisabeth-hat-kein-bett\/\" target=\"_blank\" rel=\"noreferrer noopener\">Beitrag auf dem HUB der HSLU Soziale Arbeit<\/a><br>\u2013 <a href=\"https:\/\/www.hslu.ch\/de-ch\/technik-architektur\/ueber-uns\/mediencenter\/aktuell\/2021\/08\/05\/cctp-kleinwohnformen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Webnews zur Innosuisse-Zusage f\u00fcr das Projekt<\/a><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Presse<\/h3>\n\n\n\n<p>\u2013 <a href=\"https:\/\/www.svit.ch\/de\/immobilia\/artikel\/flexibilitaet-wird-entscheidender-faktor\" id=\"https:\/\/www.svit.ch\/de\/immobilia\/artikel\/flexibilitaet-wird-entscheidender-faktor\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abFlexibilit\u00e4t wird entscheidender Faktor\u00bb online auf der Webseite von SVIT Schweiz, April 2026<\/a><br>\u2013 <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2026\/04\/Kleinwohnformen-als-Reealitaetscheck.pdf\" id=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2026\/04\/Kleinwohnformen-als-Reealitaetscheck.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abKleinwohnformen als Realit\u00e4tscheck der Schweizer Wohnpolitik\u00bb von Florentina Gojani (Verein Kleinwohnformen Schweiz) in der Zeitschrift \u00abM\u00f8dulor\u00bb, Januar 2026 (PDF)<\/a> <br>\u2013 <a href=\"https:\/\/www.energie-experten.ch\/de\/wohnen\/detail\/tiny-house-oder-mikroapartment-warum-weniger-wohnraum-vorteile-bringt.html\" id=\"https:\/\/www.energie-experten.ch\/de\/wohnen\/detail\/tiny-house-oder-mikroapartment-warum-weniger-wohnraum-vorteile-bringt.html\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abTiny House oder Mikro\u00adapartment \u2013 warum weniger Wohnraum Vorteile bringt\u00bb auf dem EKZ-Blog \u00abEnergieexperten\u00bb, 09.01.2026<\/a><br>\u2013 <a href=\"https:\/\/www.fachbau.ch\/de\/product\/intelligent-bauen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abHSLU-Studie zeigt Potenzial von Kleinwohnformen\u00bb in der Zeitschrift \u00abintelligent bauen\u00bb, 28.08.2025<\/a><br>\u2013 <a href=\"https:\/\/www.das-einfamilienhaus.ch\/efh\/haus-bauen\/bauen-heute\/artikel\/250827_wohnen-in-kleinwohnungen.php\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abKleinwohnung: Weniger ist mehr\u00bb auf der Webseite des Magazins \u00abDas Einfamilienhaus\u00bb, 27.08.2025<\/a><br>\u2013 <a href=\"https:\/\/www.zofingertagblatt.ch\/wohnen-im-winzigen-haeuschen-oder-entruempeln-auf-japanisch\/\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abEntr\u00fcmpeln auf Japanisch \u2013 im Minihaus\u00bb<\/a> im Zofinger Tagblatt, 12.07.2025<br>\u2013 <a href=\"https:\/\/www.myscience.ch\/en\/news\/wire\/potenzial_von_kleinwohnformen-2025-hslu\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abPotential of small forms of housing\u00bb<\/a> <a href=\"https:\/\/www.myscience.ch\/en\/news\/wire\/potenzial_von_kleinwohnformen-2025-hslu\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><a href=\"https:\/\/www.myscience.ch\/en\/news\/wire\/potenzial_von_kleinwohnformen-2025-hslu\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a>auf MyScience (engl.)<br>\u2013 <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/05\/Kleinwohnformen.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abKleinwohnformen wie Tiny Houses haben grosses Marktpotenzial\u00bb in der <\/a>Luzerner Zeitung und diversen weiteren Titeln der CH Media , 08.05.2025<br>\u2013 <a href=\"https:\/\/www.blick.ch\/green-circle\/der-trend-der-tiny-houses-mehr-lebensqualitaet-auf-30-quadratmetern-id20733885.html\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abMehr Lebensqualit\u00e4t auf 30 Quadratmetern\u00bb<\/a> im Blick , 05.04.2025<br>\u2013 <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2024\/10\/WR_10-24_SelinaLutz_final.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abKnapp bemessen\u00bb in der Wohnrevue, 10\/2024<\/a><br>\u2013 <a href=\"https:\/\/www.srf.ch\/audio\/rendez-vous\/tiny-houses-eine-attraktive-wohnform-mit-hindernissen?partId=12659954\" target=\"_blank\" rel=\"noreferrer noopener\">SRF Radiosendung \u00abRendez-vous\u00bb zum Thema mit einem Interview der Projektleiterin Selina Lutz<\/a><br>\u2013 <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2024\/03\/Artikel_Wohngenossenschaften_02_2024.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abKleinwohnformen haben Potenzial\u00bb in WOHNEN Wohnbaugenossenschaften Schweiz 02\/2024<\/a><br>\u2013 <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2024\/02\/LZHP-240127-025.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abLieber mehr Licht als grosse R\u00e4ume\u00bb in der Luzerner Zeitung, 27.01.2024<\/a><br>\u2013 <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2023\/10\/Tiny-House_NZZ_141023.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Artikel \u00abMan darf nicht kompliziert sein\u00bb in der NZZ, 14.10.2023<\/a><br>\u2013 <a href=\"https:\/\/news.hslu.ch\/kleinwohnformen\/\" target=\"_blank\" rel=\"noreferrer noopener\">Beitrag zum Projekt auf \u00abHSLU News &amp; Stories\u00bb<\/a><br>\u2013 <a href=\"https:\/\/www.srf.ch\/audio\/trend\/tiny-house-wohnen-auf-kleinem-raum-ist-kein-kinderspiel?id=11980067\" target=\"_blank\" rel=\"noreferrer noopener\">Beitrag in der SRF Radiosendung \u00abTrend\u00bb mit einem Interview der Projektleiterin Selina Lutz<\/a><br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Kontakt<\/h3>\n\n\n\n<p>Selina Lutz<br>Projektleiterin<br>+41 41 349 37 72<br><a href=\"&#x6d;&#x61;&#105;&#108;to&#x3a;&#x73;&#x65;&#108;in&#x61;&#x2e;&#x6c;&#117;&#116;z&#x40;&#x68;&#x73;&#108;&#117;&#46;&#x63;&#x68;\" target=\"_blank\" rel=\"noreferrer noopener\">&#x73;&#101;l&#x69;&#110;a&#x2e;&#108;u&#x74;&#122;&#64;&#x68;&#115;l&#x75;&#x2e;c&#x68;<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wohn- und Lebensraum mit Potenzial? Klimawandel, Bauland-Mangel und steigende Mieten \u2013 der Immobiliensektor steht vor grossen Herausforderungen. Ein interdisziplin\u00e4res Forschungsprojekt untersucht das Potenzial von Kleinwohnformen wie Tiny Houses, Micro-Apartments und [&hellip;]<\/p>\n","protected":false},"author":44,"featured_media":39114,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[39,33],"tags":[],"class_list":["post-9529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cctp-projekte","category-forschung"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kleinwohnformen - Architektur an der Hochschule Luzern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kleinwohnformen - Architektur an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"Wohn- und Lebensraum mit Potenzial? Klimawandel, Bauland-Mangel und steigende Mieten \u2013 der Immobiliensektor steht vor grossen Herausforderungen. Ein interdisziplin\u00e4res Forschungsprojekt untersucht das Potenzial von Kleinwohnformen wie Tiny Houses, Micro-Apartments und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/\" \/>\n<meta property=\"og:site_name\" content=\"Architektur an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-09T11:20:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-29T06:48:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Hauptseite_1920px.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1438\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jaramalevez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"jaramalevez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/\"},\"author\":{\"name\":\"jaramalevez\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#\\\/schema\\\/person\\\/001cee0914381b1d1d390e0f07da2aad\"},\"headline\":\"Kleinwohnformen\",\"datePublished\":\"2022-05-09T11:20:00+00:00\",\"dateModified\":\"2026-04-29T06:48:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/\"},\"wordCount\":1834,\"image\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/05\\\/Bild_Hauptseite_1920px.jpg\",\"articleSection\":[\"CCTP Projekte\",\"Forschung\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/\",\"name\":\"Kleinwohnformen - Architektur an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/05\\\/Bild_Hauptseite_1920px.jpg\",\"datePublished\":\"2022-05-09T11:20:00+00:00\",\"dateModified\":\"2026-04-29T06:48:34+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#\\\/schema\\\/person\\\/001cee0914381b1d1d390e0f07da2aad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/05\\\/Bild_Hauptseite_1920px.jpg\",\"contentUrl\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2022\\\/05\\\/Bild_Hauptseite_1920px.jpg\",\"width\":1920,\"height\":1438,\"caption\":\"The couple relax outdoors in a tiny house , spend the weekend in nature.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/kleinwohnformen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kleinwohnformen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#website\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/\",\"name\":\"Architektur an der Hochschule Luzern\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#\\\/schema\\\/person\\\/001cee0914381b1d1d390e0f07da2aad\",\"name\":\"jaramalevez\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/author\\\/jaramalevez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kleinwohnformen - Architektur an der Hochschule Luzern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/","og_locale":"de_DE","og_type":"article","og_title":"Kleinwohnformen - Architektur an der Hochschule Luzern","og_description":"Wohn- und Lebensraum mit Potenzial? Klimawandel, Bauland-Mangel und steigende Mieten \u2013 der Immobiliensektor steht vor grossen Herausforderungen. Ein interdisziplin\u00e4res Forschungsprojekt untersucht das Potenzial von Kleinwohnformen wie Tiny Houses, Micro-Apartments und [&hellip;]","og_url":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/","og_site_name":"Architektur an der Hochschule Luzern","article_published_time":"2022-05-09T11:20:00+00:00","article_modified_time":"2026-04-29T06:48:34+00:00","og_image":[{"width":1920,"height":1438,"url":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Hauptseite_1920px.jpg","type":"image\/jpeg"}],"author":"jaramalevez","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"jaramalevez","Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/#article","isPartOf":{"@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/"},"author":{"name":"jaramalevez","@id":"https:\/\/sites.hslu.ch\/architektur\/#\/schema\/person\/001cee0914381b1d1d390e0f07da2aad"},"headline":"Kleinwohnformen","datePublished":"2022-05-09T11:20:00+00:00","dateModified":"2026-04-29T06:48:34+00:00","mainEntityOfPage":{"@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/"},"wordCount":1834,"image":{"@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/#primaryimage"},"thumbnailUrl":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Hauptseite_1920px.jpg","articleSection":["CCTP Projekte","Forschung"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/","url":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/","name":"Kleinwohnformen - Architektur an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/sites.hslu.ch\/architektur\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/#primaryimage"},"image":{"@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/#primaryimage"},"thumbnailUrl":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Hauptseite_1920px.jpg","datePublished":"2022-05-09T11:20:00+00:00","dateModified":"2026-04-29T06:48:34+00:00","author":{"@id":"https:\/\/sites.hslu.ch\/architektur\/#\/schema\/person\/001cee0914381b1d1d390e0f07da2aad"},"breadcrumb":{"@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/#primaryimage","url":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Hauptseite_1920px.jpg","contentUrl":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2022\/05\/Bild_Hauptseite_1920px.jpg","width":1920,"height":1438,"caption":"The couple relax outdoors in a tiny house , spend the weekend in nature."},{"@type":"BreadcrumbList","@id":"https:\/\/sites.hslu.ch\/architektur\/kleinwohnformen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sites.hslu.ch\/architektur\/"},{"@type":"ListItem","position":2,"name":"Kleinwohnformen"}]},{"@type":"WebSite","@id":"https:\/\/sites.hslu.ch\/architektur\/#website","url":"https:\/\/sites.hslu.ch\/architektur\/","name":"Architektur an der Hochschule Luzern","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sites.hslu.ch\/architektur\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/sites.hslu.ch\/architektur\/#\/schema\/person\/001cee0914381b1d1d390e0f07da2aad","name":"jaramalevez","url":"https:\/\/sites.hslu.ch\/architektur\/author\/jaramalevez\/"}]}},"_links":{"self":[{"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/posts\/9529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/comments?post=9529"}],"version-history":[{"count":56,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/posts\/9529\/revisions"}],"predecessor-version":[{"id":49953,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/posts\/9529\/revisions\/49953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/media\/39114"}],"wp:attachment":[{"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/media?parent=9529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/categories?post=9529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/tags?post=9529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}