{"id":45646,"date":"2024-08-02T11:27:00","date_gmt":"2024-08-02T09:27:00","guid":{"rendered":"https:\/\/sites.hslu.ch\/architektur\/?p=45646"},"modified":"2025-09-18T12:09:55","modified_gmt":"2025-09-18T10:09:55","slug":"bauberatung-in-gemeinden","status":"publish","type":"post","link":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/","title":{"rendered":"Bauberatung in Gemeinden"},"content":{"rendered":"\n<p class=\"is-style-lead-text wp-block-paragraph\">Bauberatung ist ein zentrales Instrument, um eine hohe Baukultur zu gew\u00e4hrleisten. Im Forschungsprojekt \u00abBauberatung in Gemeinden\u00bb wurden bestehende Formen von Bauberatung evaluiert und Guidelines f\u00fcr kleinere Gemeinden erarbeitet, die aufzeigen, wie effektive und effiziente Bauberatung implementiert werden kann. Die aus dem Projekt resultierende Brosch\u00fcre hilft Gemeinden, eine auf ihre Bed\u00fcrfnisse angepasste Bauberatung auszuw\u00e4hlen und einzuf\u00fchren. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Hintergrund und Inhalt des Projektes<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gemeinden sind aufgefordert, auf eine Siedlungsentwicklung nach innen zu fokussieren. Durch den Bev\u00f6lkerungswachstum erh\u00f6ht sich der Druck auf die bereits bebauten Siedlungsgebiete. Daneben sorgt der Strukturwandel in der Landwirtschaft f\u00fcr Herausforderungen ausserhalb des Siedlungsgebietes. Bezieht sich die bauliche Entwicklung nicht auf den vorhandenen Kontext, kann dies zu Konflikten mit bestehenden Orts- und Land\u00adschaftsbildern f\u00fchren. Es gilt, Ortsbilder nicht einzufrieren, den Bestand jedoch zu respektieren und qualit\u00e4tsvoll weiterzuentwickeln. Schliesslich soll eine hohe Bau\u00adkultur in der Gemeindeentwicklung gew\u00e4hr\u00adleistet werden. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses Forschungsprojekt soll M\u00f6glichkeiten aufzuzeigen, wie die Bauberatung als Instrument in Gemeinden breiter verankert werden kann. Bestehende Auspr\u00e4gungen von Bauberatung wurden reflektiert und es wurden Varianten f\u00fcr kleine und mittlere Gemein\u00adden evaluiert \u2013 damit diese mit ihren beschr\u00e4nkten Res\u00adsourcen eine m\u00f6glichst wirkungsvolle und effiziente Bauberatung f\u00fcr die Ortsbildgestaltung implementieren k\u00f6n\u00adnen. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine der vorgeschlagenen Varianten, ist die Implementierung einer regionalen Bauberatung. Dieser Ansatz erm\u00f6glicht es, Synergien gezielt zu nutzen. Eine Umsetzung soll nun im Entlebuch im Kanton Luzern in einem Pilotprojekt getestet werden. Das Pilotprojekt\u00a0liefert wiederum wichtige Erkenntnisse, die generalisiert werden k\u00f6nnen. Durch dieses Vorgehen soll die Praxistauglichkeit\u00a0der Erkenntnisse\u00a0gew\u00e4hrleistet werden, damit\u00a0weitere\u00a0Kantone\u00a0und Gemeinden\u00a0davon profitieren\u00a0k\u00f6nnen.\u00bb<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Auszug aus der Brosch\u00fcre \u00abBauberatung in Gemeinden \u2013 eine Bauberatung konzipieren und einf\u00fchren\u00bb<\/h3>\n\n\n    <div class=\"ms-gallery \">\n        <div class=\"ms-gallery-sizer\"><\/div>\n        <div class=\"ms-gallery-gutter\"><\/div>\n                                        <div class=\"ms-gallery-item narrow\">\n                                                            <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-1bis.jpg\" data-lightbox=\"masonery-gallery\"  data-size=\"narrow\"  data-title=\"\" data-alt=\"\">\n                        <img decoding=\"async\" class=\"ms-gallery-item__image\"  data-size=\"narrow\"  src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-1bis.jpg\" alt=\"\" \/>\n                    <\/a>\n                                        <\/div>\n\n                                                                    <div class=\"ms-gallery-item narrow\">\n                                                            <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-2bis.jpg\" data-lightbox=\"masonery-gallery\"  data-size=\"narrow\"  data-title=\"\" data-alt=\"\">\n                        <img decoding=\"async\" class=\"ms-gallery-item__image\"  data-size=\"narrow\"  src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-2bis.jpg\" alt=\"\" \/>\n                    <\/a>\n                                        <\/div>\n\n                                                                    <div class=\"ms-gallery-item narrow\">\n                                                            <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-3bis.jpg\" data-lightbox=\"masonery-gallery\"  data-size=\"narrow\"  data-title=\"\" data-alt=\"\">\n                        <img decoding=\"async\" class=\"ms-gallery-item__image\"  data-size=\"narrow\"  src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-3bis.jpg\" alt=\"\" \/>\n                    <\/a>\n                                        <\/div>\n\n                                                                    <div class=\"ms-gallery-item narrow\">\n                                                            <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-14.jpg\" data-lightbox=\"masonery-gallery\"  data-size=\"narrow\"  data-title=\"\" data-alt=\"\">\n                        <img decoding=\"async\" class=\"ms-gallery-item__image\"  data-size=\"narrow\"  src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-14.jpg\" alt=\"\" \/>\n                    <\/a>\n                                        <\/div>\n\n                                                                    <div class=\"ms-gallery-item narrow\">\n                                                            <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-15.jpg\" data-lightbox=\"masonery-gallery\"  data-size=\"narrow\"  data-title=\"\" data-alt=\"\">\n                        <img decoding=\"async\" class=\"ms-gallery-item__image\"  data-size=\"narrow\"  src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-15.jpg\" alt=\"\" \/>\n                    <\/a>\n                                        <\/div>\n\n                                                                    <div class=\"ms-gallery-item narrow\">\n                                                            <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-16.jpg\" data-lightbox=\"masonery-gallery\"  data-size=\"narrow\"  data-title=\"\" data-alt=\"\">\n                        <img decoding=\"async\" class=\"ms-gallery-item__image\"  data-size=\"narrow\"  src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-16.jpg\" alt=\"\" \/>\n                    <\/a>\n                                        <\/div>\n\n                                                                    <div class=\"ms-gallery-item narrow\">\n                                                            <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-30.jpg\" data-lightbox=\"masonery-gallery\"  data-size=\"narrow\"  data-title=\"\" data-alt=\"\">\n                        <img decoding=\"async\" class=\"ms-gallery-item__image\"  data-size=\"narrow\"  src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-30.jpg\" alt=\"\" \/>\n                    <\/a>\n                                        <\/div>\n\n                                                                    <div class=\"ms-gallery-item narrow\">\n                                                            <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-32.jpg\" data-lightbox=\"masonery-gallery\"  data-size=\"narrow\"  data-title=\"\" data-alt=\"\">\n                        <img decoding=\"async\" class=\"ms-gallery-item__image\"  data-size=\"narrow\"  src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-32.jpg\" alt=\"\" \/>\n                    <\/a>\n                                        <\/div>\n\n                                                                    <div class=\"ms-gallery-item narrow\">\n                                                            <a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-33.jpg\" data-lightbox=\"masonery-gallery\"  data-size=\"narrow\"  data-title=\"\" data-alt=\"\">\n                        <img decoding=\"async\" class=\"ms-gallery-item__image\"  data-size=\"narrow\"  src=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-33.jpg\" alt=\"\" \/>\n                    <\/a>\n                                        <\/div>\n\n                                                    <div class=\"ms-gallery-item narrow\">\n                <\/div>\n                <\/div>\n            \n\n\n<h3 class=\"wp-block-heading\">Organisation<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Projektleitung<\/strong><br>Stephan K\u00e4ppeli, Hochschule Luzern \u2013 Wirtschaft<br>Stefan Kunz, Hochschule Luzern \u2013 Technik &amp; Architektur, Institut f\u00fcr Architektur, CCTP<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Externe Projektpartner<\/strong><br>\u2013 <a href=\"http:\/\/www.fhgr.ch\" target=\"_blank\" rel=\"noreferrer noopener\">Fachhochschule Graub\u00fcnden<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Finanzierung<\/strong><br>\u2013 Andere Bundesstellen<br>\u2013 \u00d6ffentliche Hand<br> \u2013 <a href=\"https:\/\/sites.hslu.ch\/itc\/raum-gesellschaft\/\" target=\"_blank\" rel=\"noreferrer noopener\">ITC Raum und Gesellschaft<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Laufzeit<\/strong>: 01.02.2022-01.08.2023<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Links und Downloads<\/h3>\n\n\n\n<ul class=\"wp-block-list is-style-list-dash\">\n<li><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/BB_CH_Schlussbericht_final.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Schlussbericht Bauberatung in Gemeinden<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">Brosch\u00fcre \u00abBauberatung in Gemeinden\u00bb<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.hslu.ch\/de-ch\/hochschule-luzern\/forschung\/projekte\/detail\/?pid=6380\" target=\"_blank\" rel=\"noreferrer noopener\">Das Pilotprojekt \u00abBauberatung UNESCO Biosph\u00e4re Entlebuch\u00bb gibt Einblick in eine konkrete Umsetzung <\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Kontakt<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Stefan Kunz<br>Projektleiter<br>Institut f\u00fcr Architektur (IAR)<br>Kompetenzzentrum Typologie &amp; Planung in Architektur (CCTP)<br><a href=\"&#109;&#x61;i&#x6c;t&#111;&#x3a;&#115;&#x74;e&#102;&#x61;&#110;&#x2e;k&#x75;&#x6e;&#122;&#x40;h&#x73;l&#117;&#x2e;&#99;&#x68;\" target=\"_blank\" rel=\"noreferrer noopener\">&#115;&#x74;&#x65;f&#97;&#x6e;&#46;&#107;&#x75;n&#122;&#x40;h&#115;&#x6c;&#x75;&#46;&#x63;&#x68;<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bauberatung ist ein zentrales Instrument, um eine hohe Baukultur zu gew\u00e4hrleisten. Im Forschungsprojekt \u00abBauberatung in Gemeinden\u00bb wurden bestehende Formen von Bauberatung evaluiert und Guidelines f\u00fcr kleinere Gemeinden erarbeitet, die aufzeigen, wie effektive und effiziente Bauberatung implementiert werden kann. Die aus dem Projekt resultierende Brosch\u00fcre hilft Gemeinden, eine auf ihre Bed\u00fcrfnisse angepasste Bauberatung auszuw\u00e4hlen und einzuf\u00fchren. <\/p>\n","protected":false},"author":44,"featured_media":45680,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[39,33,234,22,88],"tags":[],"class_list":["post-45646","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cctp-projekte","category-forschung","category-fs2023","category-semester-jahr","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bauberatung in Gemeinden - Architektur an der Hochschule Luzern<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bauberatung in Gemeinden - Architektur an der Hochschule Luzern\" \/>\n<meta property=\"og:description\" content=\"Bauberatung ist ein zentrales Instrument, um eine hohe Baukultur zu gew\u00e4hrleisten. Im Forschungsprojekt \u00abBauberatung in Gemeinden\u00bb wurden bestehende Formen von Bauberatung evaluiert und Guidelines f\u00fcr kleinere Gemeinden erarbeitet, die aufzeigen, wie effektive und effiziente Bauberatung implementiert werden kann. Die aus dem Projekt resultierende Brosch\u00fcre hilft Gemeinden, eine auf ihre Bed\u00fcrfnisse angepasste Bauberatung auszuw\u00e4hlen und einzuf\u00fchren.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/\" \/>\n<meta property=\"og:site_name\" content=\"Architektur an der Hochschule Luzern\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-02T09:27:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-18T10:09:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"929\" \/>\n\t<meta property=\"og:image:height\" content=\"1099\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"jaramalevez\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"jaramalevez\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/\"},\"author\":{\"name\":\"jaramalevez\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#\\\/schema\\\/person\\\/001cee0914381b1d1d390e0f07da2aad\"},\"headline\":\"Bauberatung in Gemeinden\",\"datePublished\":\"2024-08-02T09:27:00+00:00\",\"dateModified\":\"2025-09-18T10:09:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/\"},\"wordCount\":370,\"image\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/09\\\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg\",\"articleSection\":[\"CCTP Projekte\",\"Forschung\",\"FS2023\",\"Semester\\\/Jahr\",\"Uncategorized\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/\",\"name\":\"Bauberatung in Gemeinden - Architektur an der Hochschule Luzern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/09\\\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg\",\"datePublished\":\"2024-08-02T09:27:00+00:00\",\"dateModified\":\"2025-09-18T10:09:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#\\\/schema\\\/person\\\/001cee0914381b1d1d390e0f07da2aad\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/#primaryimage\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/09\\\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg\",\"contentUrl\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/wp-content\\\/uploads\\\/sites\\\/11\\\/2025\\\/09\\\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg\",\"width\":929,\"height\":1099},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/bauberatung-in-gemeinden\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bauberatung in Gemeinden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#website\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/\",\"name\":\"Architektur an der Hochschule Luzern\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/#\\\/schema\\\/person\\\/001cee0914381b1d1d390e0f07da2aad\",\"name\":\"jaramalevez\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/architektur\\\/author\\\/jaramalevez\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bauberatung in Gemeinden - Architektur an der Hochschule Luzern","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/","og_locale":"de_DE","og_type":"article","og_title":"Bauberatung in Gemeinden - Architektur an der Hochschule Luzern","og_description":"Bauberatung ist ein zentrales Instrument, um eine hohe Baukultur zu gew\u00e4hrleisten. Im Forschungsprojekt \u00abBauberatung in Gemeinden\u00bb wurden bestehende Formen von Bauberatung evaluiert und Guidelines f\u00fcr kleinere Gemeinden erarbeitet, die aufzeigen, wie effektive und effiziente Bauberatung implementiert werden kann. Die aus dem Projekt resultierende Brosch\u00fcre hilft Gemeinden, eine auf ihre Bed\u00fcrfnisse angepasste Bauberatung auszuw\u00e4hlen und einzuf\u00fchren.","og_url":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/","og_site_name":"Architektur an der Hochschule Luzern","article_published_time":"2024-08-02T09:27:00+00:00","article_modified_time":"2025-09-18T10:09:55+00:00","og_image":[{"width":929,"height":1099,"url":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg","type":"image\/jpeg"}],"author":"jaramalevez","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"jaramalevez","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/#article","isPartOf":{"@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/"},"author":{"name":"jaramalevez","@id":"https:\/\/sites.hslu.ch\/architektur\/#\/schema\/person\/001cee0914381b1d1d390e0f07da2aad"},"headline":"Bauberatung in Gemeinden","datePublished":"2024-08-02T09:27:00+00:00","dateModified":"2025-09-18T10:09:55+00:00","mainEntityOfPage":{"@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/"},"wordCount":370,"image":{"@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/#primaryimage"},"thumbnailUrl":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg","articleSection":["CCTP Projekte","Forschung","FS2023","Semester\/Jahr","Uncategorized"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/","url":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/","name":"Bauberatung in Gemeinden - Architektur an der Hochschule Luzern","isPartOf":{"@id":"https:\/\/sites.hslu.ch\/architektur\/#website"},"primaryImageOfPage":{"@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/#primaryimage"},"image":{"@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/#primaryimage"},"thumbnailUrl":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg","datePublished":"2024-08-02T09:27:00+00:00","dateModified":"2025-09-18T10:09:55+00:00","author":{"@id":"https:\/\/sites.hslu.ch\/architektur\/#\/schema\/person\/001cee0914381b1d1d390e0f07da2aad"},"breadcrumb":{"@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/#primaryimage","url":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg","contentUrl":"https:\/\/sites.hslu.ch\/architektur\/wp-content\/uploads\/sites\/11\/2025\/09\/HSLU_Bauberatung_Broschuere-Titelgrafik.jpg","width":929,"height":1099},{"@type":"BreadcrumbList","@id":"https:\/\/sites.hslu.ch\/architektur\/bauberatung-in-gemeinden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sites.hslu.ch\/architektur\/"},{"@type":"ListItem","position":2,"name":"Bauberatung in Gemeinden"}]},{"@type":"WebSite","@id":"https:\/\/sites.hslu.ch\/architektur\/#website","url":"https:\/\/sites.hslu.ch\/architektur\/","name":"Architektur an der Hochschule Luzern","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sites.hslu.ch\/architektur\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/sites.hslu.ch\/architektur\/#\/schema\/person\/001cee0914381b1d1d390e0f07da2aad","name":"jaramalevez","url":"https:\/\/sites.hslu.ch\/architektur\/author\/jaramalevez\/"}]}},"_links":{"self":[{"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/posts\/45646","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/comments?post=45646"}],"version-history":[{"count":13,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/posts\/45646\/revisions"}],"predecessor-version":[{"id":45705,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/posts\/45646\/revisions\/45705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/media\/45680"}],"wp:attachment":[{"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/media?parent=45646"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/categories?post=45646"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sites.hslu.ch\/architektur\/wp-json\/wp\/v2\/tags?post=45646"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}