{"id":188,"count":9,"description":"","link":"https:\/\/sites.hslu.ch\/applied-data-science\/themen\/data-science-research-and-project-portrait\/","name":"Data Science Research and Project Portrait","slug":"data-science-research-and-project-portrait","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Data Science Research and Project Portrait Archives - Applied Data Science<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sites.hslu.ch\/applied-data-science\/themen\/data-science-research-and-project-portrait\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Data Science Research and Project Portrait Archives - Applied Data Science\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sites.hslu.ch\/applied-data-science\/themen\/data-science-research-and-project-portrait\/\" \/>\n<meta property=\"og:site_name\" content=\"Applied Data Science\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/applied-data-science\\\/themen\\\/data-science-research-and-project-portrait\\\/\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/applied-data-science\\\/themen\\\/data-science-research-and-project-portrait\\\/\",\"name\":\"Data Science Research and Project Portrait Archives - Applied Data Science\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/applied-data-science\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/applied-data-science\\\/themen\\\/data-science-research-and-project-portrait\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/applied-data-science\\\/themen\\\/data-science-research-and-project-portrait\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sites.hslu.ch\\\/applied-data-science\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Data Science Research and Project Portrait\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sites.hslu.ch\\\/applied-data-science\\\/#website\",\"url\":\"https:\\\/\\\/sites.hslu.ch\\\/applied-data-science\\\/\",\"name\":\"Applied Data Science\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/sites.hslu.ch\\\/applied-data-science\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Data Science Research and Project Portrait Archives - Applied Data Science","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sites.hslu.ch\/applied-data-science\/themen\/data-science-research-and-project-portrait\/","og_locale":"en_US","og_type":"article","og_title":"Data Science Research and Project Portrait Archives - Applied Data Science","og_url":"https:\/\/sites.hslu.ch\/applied-data-science\/themen\/data-science-research-and-project-portrait\/","og_site_name":"Applied Data Science","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/sites.hslu.ch\/applied-data-science\/themen\/data-science-research-and-project-portrait\/","url":"https:\/\/sites.hslu.ch\/applied-data-science\/themen\/data-science-research-and-project-portrait\/","name":"Data Science Research and Project Portrait Archives - Applied Data Science","isPartOf":{"@id":"https:\/\/sites.hslu.ch\/applied-data-science\/#website"},"breadcrumb":{"@id":"https:\/\/sites.hslu.ch\/applied-data-science\/themen\/data-science-research-and-project-portrait\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/sites.hslu.ch\/applied-data-science\/themen\/data-science-research-and-project-portrait\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sites.hslu.ch\/applied-data-science\/"},{"@type":"ListItem","position":2,"name":"Data Science Research and Project Portrait"}]},{"@type":"WebSite","@id":"https:\/\/sites.hslu.ch\/applied-data-science\/#website","url":"https:\/\/sites.hslu.ch\/applied-data-science\/","name":"Applied Data Science","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sites.hslu.ch\/applied-data-science\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sites.hslu.ch\/applied-data-science\/wp-json\/wp\/v2\/categories\/188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sites.hslu.ch\/applied-data-science\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/sites.hslu.ch\/applied-data-science\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/sites.hslu.ch\/applied-data-science\/wp-json\/wp\/v2\/posts?categories=188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}